{"id":117280,"date":"2026-02-10T15:29:20","date_gmt":"2026-02-10T14:29:20","guid":{"rendered":"https:\/\/g-silver.com\/prodotto\/weiss-rhodiniert-anhaenger-koralle-12mm-mit-ring-5stk\/"},"modified":"2026-05-13T19:20:01","modified_gmt":"2026-05-13T17:20:01","slug":"weiss-rhodiniert-anhaenger-koralle-12mm-mit-ring-5stk","status":"publish","type":"product","link":"https:\/\/g-silver.com\/de\/produkte\/weiss-rhodiniert-anhaenger-koralle-12mm-mit-ring-5stk\/","title":{"rendered":"Weiss Rhodiniert &#8211; Anh\u00e4nger Koralle 12mm mit Ring (5Stk)"},"content":{"rendered":"<p>Artikel aus Silber 925\/1000 mit wei\u00dfer Rhodinierung.<br \/>\nRhodium wird in der Regel als Zusatzmetall f\u00fcr Silberschmuck verwendet.<\/p>\n<p>Elektrolytisch auf Silber aufgebracht, verhindert Rhodium die nat\u00fcrliche Oxidation des Silbers. Silber ist n\u00e4mlich von Natur aus oxidierbar und l\u00e4uft mit der Zeit an.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Artikel aus Silber 925\/1000 mit wei\u00dfer Rhodinierung.<br \/>\nRhodium wird in der Regel als Zusatzmetall f\u00fcr Silberschmuck verwendet.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3718],"product_tag":[],"class_list":{"0":"post-117280","1":"product","2":"type-product","3":"status-publish","5":"product_cat-uncategorized-de","7":"first","8":"instock","9":"taxable","10":"shipping-taxable","11":"purchasable","12":"product-type-simple","13":"add-to-wishlist-after_add_to_cart"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Weiss Rhodiniert - Anh\u00e4nger Koralle 12mm mit Ring (5Stk) | G-Silver<\/title>\n<meta name=\"description\" content=\"In der Kategorie Sterling Silber Schmuckzubeh\u00f6r finden Sie in Pl\u00e4ttchen und Anh\u00e4nger diesen Artikel aus Silber 925\/1000 mit wei\u00dfer Rhodinierung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/g-silver.com\/de\/produkte\/weiss-rhodiniert-anhaenger-koralle-12mm-mit-ring-5stk\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weiss Rhodiniert - Anh\u00e4nger Koralle 12mm mit Ring (5Stk)\" \/>\n<meta property=\"og:description\" content=\"In der Kategorie Sterling Silber Schmuckzubeh\u00f6r finden Sie in Pl\u00e4ttchen und Anh\u00e4nger diesen Artikel aus Silber 925\/1000 mit wei\u00dfer Rhodinierung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/g-silver.com\/de\/produkte\/weiss-rhodiniert-anhaenger-koralle-12mm-mit-ring-5stk\/\" \/>\n<meta property=\"og:site_name\" content=\"G-Silver\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063277505032\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T17:20:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/g-silver.com\/wp-content\/uploads\/2025\/03\/Valise-de-Logo_G-Silver_LogoBaseline_1_Background-degrade.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2480\" \/>\n\t<meta property=\"og:image:height\" content=\"1748\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"Auf Lager\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/g-silver.com\/de\/produkte\/weiss-rhodiniert-anhaenger-koralle-12mm-mit-ring-5stk\/\",\"url\":\"https:\/\/g-silver.com\/de\/produkte\/weiss-rhodiniert-anhaenger-koralle-12mm-mit-ring-5stk\/\",\"name\":\"Weiss Rhodiniert - Anh\u00e4nger Koralle 12mm mit Ring (5Stk) | G-Silver\",\"isPartOf\":{\"@id\":\"https:\/\/g-silver.com\/#website\"},\"datePublished\":\"2026-02-10T14:29:20+00:00\",\"dateModified\":\"2026-05-13T17:20:01+00:00\",\"description\":\"In der Kategorie Sterling Silber Schmuckzubeh\u00f6r finden Sie in Pl\u00e4ttchen und Anh\u00e4nger diesen Artikel aus Silber 925\/1000 mit wei\u00dfer Rhodinierung.\",\"breadcrumb\":{\"@id\":\"https:\/\/g-silver.com\/de\/produkte\/weiss-rhodiniert-anhaenger-koralle-12mm-mit-ring-5stk\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/g-silver.com\/de\/produkte\/weiss-rhodiniert-anhaenger-koralle-12mm-mit-ring-5stk\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/g-silver.com\/de\/produkte\/weiss-rhodiniert-anhaenger-koralle-12mm-mit-ring-5stk\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/g-silver.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uncategorized\",\"item\":\"https:\/\/g-silver.com\/de\/produktkategorie\/uncategorized-de\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Weiss Rhodiniert &#8211; Anh\u00e4nger Koralle 12mm mit Ring (5Stk)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/g-silver.com\/#website\",\"url\":\"https:\/\/g-silver.com\/\",\"name\":\"G-Silver\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/g-silver.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/g-silver.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/g-silver.com\/#organization\",\"name\":\"G-Silver\",\"url\":\"https:\/\/g-silver.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/g-silver.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/g-silver.com\/wp-content\/uploads\/2025\/03\/G-Silver__Short-Logo.jpg\",\"contentUrl\":\"https:\/\/g-silver.com\/wp-content\/uploads\/2025\/03\/G-Silver__Short-Logo.jpg\",\"width\":1182,\"height\":1182,\"caption\":\"G-Silver\"},\"image\":{\"@id\":\"https:\/\/g-silver.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063277505032\",\"https:\/\/www.instagram.com\/g_silver_com\/\"]}]}<\/script>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"COR12-RB\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Weiss Rhodiniert - Anh\u00e4nger Koralle 12mm mit Ring (5Stk) | G-Silver","description":"In der Kategorie Sterling Silber Schmuckzubeh\u00f6r finden Sie in Pl\u00e4ttchen und Anh\u00e4nger diesen Artikel aus Silber 925\/1000 mit wei\u00dfer Rhodinierung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/g-silver.com\/de\/produkte\/weiss-rhodiniert-anhaenger-koralle-12mm-mit-ring-5stk\/","og_locale":"de_DE","og_type":"article","og_title":"Weiss Rhodiniert - Anh\u00e4nger Koralle 12mm mit Ring (5Stk)","og_description":"In der Kategorie Sterling Silber Schmuckzubeh\u00f6r finden Sie in Pl\u00e4ttchen und Anh\u00e4nger diesen Artikel aus Silber 925\/1000 mit wei\u00dfer Rhodinierung.","og_url":"https:\/\/g-silver.com\/de\/produkte\/weiss-rhodiniert-anhaenger-koralle-12mm-mit-ring-5stk\/","og_site_name":"G-Silver","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063277505032","article_modified_time":"2026-05-13T17:20:01+00:00","og_image":[{"width":2480,"height":1748,"url":"https:\/\/g-silver.com\/wp-content\/uploads\/2025\/03\/Valise-de-Logo_G-Silver_LogoBaseline_1_Background-degrade.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verf\u00fcgbarkeit":"Auf Lager"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/g-silver.com\/de\/produkte\/weiss-rhodiniert-anhaenger-koralle-12mm-mit-ring-5stk\/","url":"https:\/\/g-silver.com\/de\/produkte\/weiss-rhodiniert-anhaenger-koralle-12mm-mit-ring-5stk\/","name":"Weiss Rhodiniert - Anh\u00e4nger Koralle 12mm mit Ring (5Stk) | G-Silver","isPartOf":{"@id":"https:\/\/g-silver.com\/#website"},"datePublished":"2026-02-10T14:29:20+00:00","dateModified":"2026-05-13T17:20:01+00:00","description":"In der Kategorie Sterling Silber Schmuckzubeh\u00f6r finden Sie in Pl\u00e4ttchen und Anh\u00e4nger diesen Artikel aus Silber 925\/1000 mit wei\u00dfer Rhodinierung.","breadcrumb":{"@id":"https:\/\/g-silver.com\/de\/produkte\/weiss-rhodiniert-anhaenger-koralle-12mm-mit-ring-5stk\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/g-silver.com\/de\/produkte\/weiss-rhodiniert-anhaenger-koralle-12mm-mit-ring-5stk\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/g-silver.com\/de\/produkte\/weiss-rhodiniert-anhaenger-koralle-12mm-mit-ring-5stk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/g-silver.com\/de\/"},{"@type":"ListItem","position":2,"name":"Uncategorized","item":"https:\/\/g-silver.com\/de\/produktkategorie\/uncategorized-de\/"},{"@type":"ListItem","position":3,"name":"Weiss Rhodiniert &#8211; Anh\u00e4nger Koralle 12mm mit Ring (5Stk)"}]},{"@type":"WebSite","@id":"https:\/\/g-silver.com\/#website","url":"https:\/\/g-silver.com\/","name":"G-Silver","description":"","publisher":{"@id":"https:\/\/g-silver.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/g-silver.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/g-silver.com\/#organization","name":"G-Silver","url":"https:\/\/g-silver.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/g-silver.com\/#\/schema\/logo\/image\/","url":"https:\/\/g-silver.com\/wp-content\/uploads\/2025\/03\/G-Silver__Short-Logo.jpg","contentUrl":"https:\/\/g-silver.com\/wp-content\/uploads\/2025\/03\/G-Silver__Short-Logo.jpg","width":1182,"height":1182,"caption":"G-Silver"},"image":{"@id":"https:\/\/g-silver.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063277505032","https:\/\/www.instagram.com\/g_silver_com\/"]}]},"og_availability":"instock","product_availability":"instock","product_retailer_item_id":"COR12-RB","product_condition":"new"},"df_price":8.6,"df_sale_price":"","df_regular_price":8.6,"df_image_link":"https:\/\/g-silver.com\/wp-content\/uploads\/woocommerce-placeholder-300x300.png","_links":{"self":[{"href":"https:\/\/g-silver.com\/de\/wp-json\/wp\/v2\/product\/117280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/g-silver.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/g-silver.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/g-silver.com\/de\/wp-json\/wp\/v2\/comments?post=117280"}],"wp:attachment":[{"href":"https:\/\/g-silver.com\/de\/wp-json\/wp\/v2\/media?parent=117280"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/g-silver.com\/de\/wp-json\/wp\/v2\/product_brand?post=117280"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/g-silver.com\/de\/wp-json\/wp\/v2\/product_cat?post=117280"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/g-silver.com\/de\/wp-json\/wp\/v2\/product_tag?post=117280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}