{"id":106575,"date":"2025-09-19T03:43:43","date_gmt":"2025-09-19T01:43:43","guid":{"rendered":"https:\/\/g-silver.com\/prodotto\/palline-ovali-ritorte-6x11mm-foro-2mm-10pz\/"},"modified":"2026-05-11T07:23:19","modified_gmt":"2026-05-11T05:23:19","slug":"palline-ovali-ritorte-6x11mm-foro-2mm-10pz","status":"publish","type":"product","link":"https:\/\/g-silver.com\/it\/prodotto\/palline-ovali-ritorte-6x11mm-foro-2mm-10pz\/","title":{"rendered":"Palline ovali ritorte 6x11mm foro 2mm (10pz)"},"content":{"rendered":"<p>Prodotto in argento 925\/1000 anallergico (senza nickel), con trattamento anti-tarnish (passivazione)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prodotto in argento 925\/1000 anallergico (senza nickel), con trattamento anti-tarnish (passivazione)<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2999,2988,3061],"product_tag":[],"class_list":{"0":"post-106575","1":"product","2":"type-product","3":"status-publish","5":"product_cat-palline-e-componenti","6":"product_cat-minuteria","7":"product_cat-ovaline","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple","15":"add-to-wishlist-after_add_to_cart"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Palline ovali ritorte 6x11mm foro 2mm (10pz) | G-Silver<\/title>\n<meta name=\"description\" content=\"Prodotto in argento 925\/1000 anallergico (senza nickel), con trattamento anti-tarnish (passivazione)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/g-silver.com\/produit\/perles-ovales-torsadees-6x11mm-trou-2mm-10pcs\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palline ovali ritorte 6x11mm foro 2mm (10pz)\" \/>\n<meta property=\"og:description\" content=\"Prodotto in argento 925\/1000 anallergico (senza nickel), con trattamento anti-tarnish (passivazione)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/g-silver.com\/produit\/perles-ovales-torsadees-6x11mm-trou-2mm-10pcs\/\" \/>\n<meta property=\"og:site_name\" content=\"G-Silver\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063277505032\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T05:23:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/g-silver.com\/wp-content\/uploads\/2025\/03\/Valise-de-Logo_G-Silver_LogoBaseline_1_Background-degrade.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2480\" \/>\n\t<meta property=\"og:image:height\" content=\"1748\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e0\" \/>\n\t<meta name=\"twitter:data1\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/g-silver.com\/produit\/perles-ovales-torsadees-6x11mm-trou-2mm-10pcs\/\",\"url\":\"https:\/\/g-silver.com\/produit\/perles-ovales-torsadees-6x11mm-trou-2mm-10pcs\/\",\"name\":\"Palline ovali ritorte 6x11mm foro 2mm (10pz) | G-Silver\",\"isPartOf\":{\"@id\":\"https:\/\/g-silver.com\/#website\"},\"datePublished\":\"2025-09-19T01:43:43+00:00\",\"dateModified\":\"2026-05-11T05:23:19+00:00\",\"description\":\"Prodotto in argento 925\/1000 anallergico (senza nickel), con trattamento anti-tarnish (passivazione)\",\"breadcrumb\":{\"@id\":\"https:\/\/g-silver.com\/produit\/perles-ovales-torsadees-6x11mm-trou-2mm-10pcs\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/g-silver.com\/produit\/perles-ovales-torsadees-6x11mm-trou-2mm-10pcs\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/g-silver.com\/produit\/perles-ovales-torsadees-6x11mm-trou-2mm-10pcs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/g-silver.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Minuteria\",\"item\":\"https:\/\/g-silver.com\/it\/categoria-prodotto\/minuteria\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PALLINE E COMPONENTI\",\"item\":\"https:\/\/g-silver.com\/it\/categoria-prodotto\/minuteria\/palline-e-componenti\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Ovaline\",\"item\":\"https:\/\/g-silver.com\/it\/categoria-prodotto\/minuteria\/palline-e-componenti\/ovaline\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Palline ovali ritorte 6x11mm foro 2mm (10pz)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/g-silver.com\/#website\",\"url\":\"https:\/\/g-silver.com\/\",\"name\":\"G-Silver\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/g-silver.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/g-silver.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/g-silver.com\/#organization\",\"name\":\"G-Silver\",\"url\":\"https:\/\/g-silver.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/g-silver.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/g-silver.com\/wp-content\/uploads\/2025\/03\/G-Silver__Short-Logo.jpg\",\"contentUrl\":\"https:\/\/g-silver.com\/wp-content\/uploads\/2025\/03\/G-Silver__Short-Logo.jpg\",\"width\":1182,\"height\":1182,\"caption\":\"G-Silver\"},\"image\":{\"@id\":\"https:\/\/g-silver.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063277505032\",\"https:\/\/www.instagram.com\/g_silver_com\/\"]}]}<\/script>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"POVT6\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Palline ovali ritorte 6x11mm foro 2mm (10pz) | G-Silver","description":"Prodotto in argento 925\/1000 anallergico (senza nickel), con trattamento anti-tarnish (passivazione)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/g-silver.com\/produit\/perles-ovales-torsadees-6x11mm-trou-2mm-10pcs\/","og_locale":"it_IT","og_type":"article","og_title":"Palline ovali ritorte 6x11mm foro 2mm (10pz)","og_description":"Prodotto in argento 925\/1000 anallergico (senza nickel), con trattamento anti-tarnish (passivazione)","og_url":"https:\/\/g-silver.com\/produit\/perles-ovales-torsadees-6x11mm-trou-2mm-10pcs\/","og_site_name":"G-Silver","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063277505032","article_modified_time":"2026-05-11T05:23:19+00:00","og_image":[{"width":2480,"height":1748,"url":"https:\/\/g-silver.com\/wp-content\/uploads\/2025\/03\/Valise-de-Logo_G-Silver_LogoBaseline_1_Background-degrade.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e0":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/g-silver.com\/produit\/perles-ovales-torsadees-6x11mm-trou-2mm-10pcs\/","url":"https:\/\/g-silver.com\/produit\/perles-ovales-torsadees-6x11mm-trou-2mm-10pcs\/","name":"Palline ovali ritorte 6x11mm foro 2mm (10pz) | G-Silver","isPartOf":{"@id":"https:\/\/g-silver.com\/#website"},"datePublished":"2025-09-19T01:43:43+00:00","dateModified":"2026-05-11T05:23:19+00:00","description":"Prodotto in argento 925\/1000 anallergico (senza nickel), con trattamento anti-tarnish (passivazione)","breadcrumb":{"@id":"https:\/\/g-silver.com\/produit\/perles-ovales-torsadees-6x11mm-trou-2mm-10pcs\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/g-silver.com\/produit\/perles-ovales-torsadees-6x11mm-trou-2mm-10pcs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/g-silver.com\/produit\/perles-ovales-torsadees-6x11mm-trou-2mm-10pcs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/g-silver.com\/it\/"},{"@type":"ListItem","position":2,"name":"Minuteria","item":"https:\/\/g-silver.com\/it\/categoria-prodotto\/minuteria\/"},{"@type":"ListItem","position":3,"name":"PALLINE E COMPONENTI","item":"https:\/\/g-silver.com\/it\/categoria-prodotto\/minuteria\/palline-e-componenti\/"},{"@type":"ListItem","position":4,"name":"Ovaline","item":"https:\/\/g-silver.com\/it\/categoria-prodotto\/minuteria\/palline-e-componenti\/ovaline\/"},{"@type":"ListItem","position":5,"name":"Palline ovali ritorte 6x11mm foro 2mm (10pz)"}]},{"@type":"WebSite","@id":"https:\/\/g-silver.com\/#website","url":"https:\/\/g-silver.com\/","name":"G-Silver","description":"","publisher":{"@id":"https:\/\/g-silver.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/g-silver.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/g-silver.com\/#organization","name":"G-Silver","url":"https:\/\/g-silver.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/g-silver.com\/#\/schema\/logo\/image\/","url":"https:\/\/g-silver.com\/wp-content\/uploads\/2025\/03\/G-Silver__Short-Logo.jpg","contentUrl":"https:\/\/g-silver.com\/wp-content\/uploads\/2025\/03\/G-Silver__Short-Logo.jpg","width":1182,"height":1182,"caption":"G-Silver"},"image":{"@id":"https:\/\/g-silver.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063277505032","https:\/\/www.instagram.com\/g_silver_com\/"]}]},"og_availability":"instock","product_availability":"instock","product_retailer_item_id":"POVT6","product_condition":"new"},"df_price":20.1,"df_sale_price":"","df_regular_price":20.1,"df_image_link":"https:\/\/g-silver.com\/wp-content\/uploads\/woocommerce-placeholder-300x300.png","_links":{"self":[{"href":"https:\/\/g-silver.com\/it\/wp-json\/wp\/v2\/product\/106575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/g-silver.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/g-silver.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/g-silver.com\/it\/wp-json\/wp\/v2\/comments?post=106575"}],"wp:attachment":[{"href":"https:\/\/g-silver.com\/it\/wp-json\/wp\/v2\/media?parent=106575"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/g-silver.com\/it\/wp-json\/wp\/v2\/product_brand?post=106575"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/g-silver.com\/it\/wp-json\/wp\/v2\/product_cat?post=106575"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/g-silver.com\/it\/wp-json\/wp\/v2\/product_tag?post=106575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}