{"id":25246,"date":"2024-02-19T15:28:16","date_gmt":"2024-02-19T14:28:16","guid":{"rendered":"https:\/\/g-silver.com\/prodotto\/bracciale-rosario-18cm-palline-4mm-1pz\/"},"modified":"2026-05-12T04:43:55","modified_gmt":"2026-05-12T02:43:55","slug":"bracciale-rosario-18cm-palline-4mm-1pz","status":"publish","type":"product","link":"https:\/\/g-silver.com\/it\/prodotto\/bracciale-rosario-18cm-palline-4mm-1pz\/","title":{"rendered":"Bracciale rosario 18cm palline 4mm (1pz)"},"content":{"rendered":"<div id=\"isolation-scope-s9cnm15ycdxx63rxrpir620128\">Prodotto in argento 925\/1000 anallergico (senza nickel), con trattamento anti-tarnish (passivazione).<br \/>\n<br \/><b><br \/>Consigli per l&#8217;utilizzo<br \/>\n<\/b><br \/>Questo gioiello \u00e9 stato disegnato dal nostro studio di progettazione senza alcun marchio, seguendo le ultime tendenze. Puoi acquistarlo e rivenderlo con il tuo proprio logo. Beneficia del nostro savoir faire con delle collezioni pr\u00eat-\u00e0-porter.<\/p>\n<p>Leggi i nostri consigli<br \/>\n<a href=\"https:\/\/g-silver.com\/it\/blog\/focus-metier\/prendersi-cura-dei-gioielli-in-argento\" target=\"_blank\" class=\"link\" rel=\"noopener\">prendersi cura dei gioielli in argento.<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Prodotto in argento 925\/1000 anallergico (senza nickel), con trattamento anti-tarnish (passivazione)<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2998,4765,3087,2986],"product_tag":[],"class_list":{"0":"post-25246","1":"product","2":"type-product","3":"status-publish","5":"product_cat-donna","6":"product_cat-collezione-religiosa","7":"product_cat-bracciali-donna","8":"product_cat-gioielli","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple","16":"add-to-wishlist-after_add_to_cart"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bracciale rosario 18cm palline 4mm (1pz) | G-Silver<\/title>\n<meta name=\"description\" content=\"Bracciale rosario 18cm palline 4mm (1pz) - Prodotto in argento 925\/1000 anallergico (senza nickel), con trattamento anti-tarnish (passivazione). Consigli per l...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/g-silver.com\/it\/prodotto\/bracciale-rosario-18cm-palline-4mm-1pz\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bracciale rosario 18cm palline 4mm (1pz)\" \/>\n<meta property=\"og:description\" content=\"Bracciale rosario 18cm palline 4mm (1pz) - Prodotto in argento 925\/1000 anallergico (senza nickel), con trattamento anti-tarnish (passivazione). Consigli per l...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/g-silver.com\/it\/prodotto\/bracciale-rosario-18cm-palline-4mm-1pz\/\" \/>\n<meta property=\"og:site_name\" content=\"G-Silver\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063277505032\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T02:43:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/g-silver.com\/wp-content\/uploads\/2025\/03\/Valise-de-Logo_G-Silver_LogoBaseline_1_Background-degrade.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2480\" \/>\n\t<meta property=\"og:image:height\" content=\"1748\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e0\" \/>\n\t<meta name=\"twitter:data1\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/g-silver.com\/it\/prodotto\/bracciale-rosario-18cm-palline-4mm-1pz\/\",\"url\":\"https:\/\/g-silver.com\/it\/prodotto\/bracciale-rosario-18cm-palline-4mm-1pz\/\",\"name\":\"Bracciale rosario 18cm palline 4mm (1pz) | G-Silver\",\"isPartOf\":{\"@id\":\"https:\/\/g-silver.com\/#website\"},\"datePublished\":\"2024-02-19T14:28:16+00:00\",\"dateModified\":\"2026-05-12T02:43:55+00:00\",\"description\":\"Bracciale rosario 18cm palline 4mm (1pz) - Prodotto in argento 925\/1000 anallergico (senza nickel), con trattamento anti-tarnish (passivazione). Consigli per l...\",\"breadcrumb\":{\"@id\":\"https:\/\/g-silver.com\/it\/prodotto\/bracciale-rosario-18cm-palline-4mm-1pz\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/g-silver.com\/it\/prodotto\/bracciale-rosario-18cm-palline-4mm-1pz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/g-silver.com\/it\/prodotto\/bracciale-rosario-18cm-palline-4mm-1pz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/g-silver.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gioielli\",\"item\":\"https:\/\/g-silver.com\/it\/categoria-prodotto\/gioielli\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gioielli donna\",\"item\":\"https:\/\/g-silver.com\/it\/categoria-prodotto\/gioielli\/donna\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Bracciali\",\"item\":\"https:\/\/g-silver.com\/it\/categoria-prodotto\/gioielli\/donna\/bracciali-donna\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Bracciale rosario 18cm palline 4mm (1pz)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/g-silver.com\/#website\",\"url\":\"https:\/\/g-silver.com\/\",\"name\":\"G-Silver\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/g-silver.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/g-silver.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/g-silver.com\/#organization\",\"name\":\"G-Silver\",\"url\":\"https:\/\/g-silver.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/g-silver.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/g-silver.com\/wp-content\/uploads\/2025\/03\/G-Silver__Short-Logo.jpg\",\"contentUrl\":\"https:\/\/g-silver.com\/wp-content\/uploads\/2025\/03\/G-Silver__Short-Logo.jpg\",\"width\":1182,\"height\":1182,\"caption\":\"G-Silver\"},\"image\":{\"@id\":\"https:\/\/g-silver.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063277505032\",\"https:\/\/www.instagram.com\/g_silver_com\/\"]}]}<\/script>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"BRCHA04\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bracciale rosario 18cm palline 4mm (1pz) | G-Silver","description":"Bracciale rosario 18cm palline 4mm (1pz) - Prodotto in argento 925\/1000 anallergico (senza nickel), con trattamento anti-tarnish (passivazione). Consigli per l...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/g-silver.com\/it\/prodotto\/bracciale-rosario-18cm-palline-4mm-1pz\/","og_locale":"it_IT","og_type":"article","og_title":"Bracciale rosario 18cm palline 4mm (1pz)","og_description":"Bracciale rosario 18cm palline 4mm (1pz) - Prodotto in argento 925\/1000 anallergico (senza nickel), con trattamento anti-tarnish (passivazione). Consigli per l...","og_url":"https:\/\/g-silver.com\/it\/prodotto\/bracciale-rosario-18cm-palline-4mm-1pz\/","og_site_name":"G-Silver","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063277505032","article_modified_time":"2026-05-12T02:43:55+00:00","og_image":[{"width":2480,"height":1748,"url":"https:\/\/g-silver.com\/wp-content\/uploads\/2025\/03\/Valise-de-Logo_G-Silver_LogoBaseline_1_Background-degrade.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e0":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/g-silver.com\/it\/prodotto\/bracciale-rosario-18cm-palline-4mm-1pz\/","url":"https:\/\/g-silver.com\/it\/prodotto\/bracciale-rosario-18cm-palline-4mm-1pz\/","name":"Bracciale rosario 18cm palline 4mm (1pz) | G-Silver","isPartOf":{"@id":"https:\/\/g-silver.com\/#website"},"datePublished":"2024-02-19T14:28:16+00:00","dateModified":"2026-05-12T02:43:55+00:00","description":"Bracciale rosario 18cm palline 4mm (1pz) - Prodotto in argento 925\/1000 anallergico (senza nickel), con trattamento anti-tarnish (passivazione). Consigli per l...","breadcrumb":{"@id":"https:\/\/g-silver.com\/it\/prodotto\/bracciale-rosario-18cm-palline-4mm-1pz\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/g-silver.com\/it\/prodotto\/bracciale-rosario-18cm-palline-4mm-1pz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/g-silver.com\/it\/prodotto\/bracciale-rosario-18cm-palline-4mm-1pz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/g-silver.com\/it\/"},{"@type":"ListItem","position":2,"name":"Gioielli","item":"https:\/\/g-silver.com\/it\/categoria-prodotto\/gioielli\/"},{"@type":"ListItem","position":3,"name":"Gioielli donna","item":"https:\/\/g-silver.com\/it\/categoria-prodotto\/gioielli\/donna\/"},{"@type":"ListItem","position":4,"name":"Bracciali","item":"https:\/\/g-silver.com\/it\/categoria-prodotto\/gioielli\/donna\/bracciali-donna\/"},{"@type":"ListItem","position":5,"name":"Bracciale rosario 18cm palline 4mm (1pz)"}]},{"@type":"WebSite","@id":"https:\/\/g-silver.com\/#website","url":"https:\/\/g-silver.com\/","name":"G-Silver","description":"","publisher":{"@id":"https:\/\/g-silver.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/g-silver.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/g-silver.com\/#organization","name":"G-Silver","url":"https:\/\/g-silver.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/g-silver.com\/#\/schema\/logo\/image\/","url":"https:\/\/g-silver.com\/wp-content\/uploads\/2025\/03\/G-Silver__Short-Logo.jpg","contentUrl":"https:\/\/g-silver.com\/wp-content\/uploads\/2025\/03\/G-Silver__Short-Logo.jpg","width":1182,"height":1182,"caption":"G-Silver"},"image":{"@id":"https:\/\/g-silver.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063277505032","https:\/\/www.instagram.com\/g_silver_com\/"]}]},"og_availability":"instock","product_availability":"instock","product_retailer_item_id":"BRCHA04","product_condition":"new"},"df_price":20.78,"df_sale_price":"","df_regular_price":20.78,"df_image_link":"https:\/\/g-silver.com\/wp-content\/uploads\/woocommerce-placeholder-300x300.png","_links":{"self":[{"href":"https:\/\/g-silver.com\/it\/wp-json\/wp\/v2\/product\/25246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/g-silver.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/g-silver.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/g-silver.com\/it\/wp-json\/wp\/v2\/comments?post=25246"}],"wp:attachment":[{"href":"https:\/\/g-silver.com\/it\/wp-json\/wp\/v2\/media?parent=25246"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/g-silver.com\/it\/wp-json\/wp\/v2\/product_brand?post=25246"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/g-silver.com\/it\/wp-json\/wp\/v2\/product_cat?post=25246"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/g-silver.com\/it\/wp-json\/wp\/v2\/product_tag?post=25246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}